{"id":28640,"date":"2011-08-26T00:00:00","date_gmt":"2011-08-26T03:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/vejam-minha-participacao-no-programa-brasil-em-debate\/"},"modified":"2011-08-26T00:00:00","modified_gmt":"2011-08-26T03:00:00","slug":"vejam-minha-participacao-no-programa-brasil-em-debate","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/vejam-minha-participacao-no-programa-brasil-em-debate\/","title":{"rendered":"Vejam minha participa\u00e7\u00e3o no Programa Brasil em Debate"},"content":{"rendered":"<p>Para os que n&atilde;o puderam assistir a minha participa&ccedil;&atilde;o juntamente com o deputado Roberto Freire (PPS\/SP) no programa Brasil em Debate da TV C&acirc;mara. Vejam que fiz quest&atilde;o de pontuar informa&ccedil;&otilde;es, sobre o governo da presidenta Dilma, que a oposi&ccedil;&atilde;o e a grande m&iacute;dia insistem em ignorar. Vale a pena conferir!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para os que n\u00e3o puderam assistir a minha participa\u00e7\u00e3o juntamente com o deputado Roberto Freire (PPS\/SP) no programa Brasil em Debate da TV C\u00e2mara. Vejam que fiz quest\u00e3o de pontuar informa\u00e7\u00f5es, sobre o governo da presidenta Dilma, que a oposi\u00e7\u00e3o e a grande m\u00eddia insistem em ignorar. Vale a pena conferir!<\/p>\n","protected":false},"author":1,"featured_media":28639,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6827],"class_list":["post-28640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-programa-brasil-em-debate"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/28640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=28640"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/28640\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/28639"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=28640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=28640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=28640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}