{"id":28530,"date":"2011-09-02T00:00:00","date_gmt":"2011-09-02T03:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/cidades-do-noroeste-recebem-pagamento-de-verbas-federais\/"},"modified":"2011-09-02T00:00:00","modified_gmt":"2011-09-02T03:00:00","slug":"cidades-do-noroeste-recebem-pagamento-de-verbas-federais","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/cidades-do-noroeste-recebem-pagamento-de-verbas-federais\/","title":{"rendered":"Cidades do Noroeste recebem  pagamento de verbas federais"},"content":{"rendered":"<p>&nbsp;<span class=\"Apple-style-span\" style=\"font-family: verdana, sans-serif; font-size: 16px; line-height: 18px; \">As prefeituras de Terra Boa e Moreira Sales, na regi&atilde;o Noroeste do Estado, receberam esta semana o pagamento das primeiras parcelas de conv&ecirc;nios referentes a obras federais que est&atilde;o sendo realizadas nos munic&iacute;pios. Nas duas cidades est&atilde;o sendo constru&iacute;das creches que integram o Programa Proinf&acirc;ncia, do Governo Federal.<br \/>\n<\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-family: arial, sans-serif; font-size: 13px; margin-top: 0cm; margin-right: 0cm; margin-bottom: 10pt; margin-left: 0cm; text-align: justify; \"><span style=\"line-height: 18px; font-family: 'Times New Roman', serif; font-size: 12pt; \"><font face=\"verdana,sans-serif\"><br \/>\nOs dois repasses foram feitos pelo Fundo Nacional de Desenvolvimento da Educa&ccedil;&atilde;o (FNDE). Em Terra Boa o repasse foi de R$ 255.187,51, valor que corresponde a 20% do total do conv&ecirc;nio, que &eacute; de R$ 1.275.937,54. Em Moreira Sales, o repasse de R$ 264.955,33 corresponde a 40% do valor total do conv&ecirc;nio, que &eacute; de R$ 662.388,3.<\/font><\/span><\/p>\n<p class=\"MsoNormal\" style=\"font-family: arial, sans-serif; font-size: 13px; margin-top: 0cm; margin-right: 0cm; margin-bottom: 10pt; margin-left: 0cm; text-align: justify; \"><span style=\"line-height: 18px; font-family: 'Times New Roman', serif; font-size: 12pt; \"><font face=\"verdana,sans-serif\">&ldquo;Estes munic&iacute;pios t&ecirc;m todos os motivos para comemorar estas conquistas, que v&atilde;o proporcionar melhores condi&ccedil;&otilde;es de atendimento para centenas de crian&ccedil;as, numa das fases mais importantes para o desenvolvimento intelectual&rdquo;, afirma o deputado Zeca Dirceu.<\/font><\/span><\/p>\n<div class=\"MsoNormal\" style=\"font-family: arial, sans-serif; font-size: 13px; margin-top: 0cm; margin-right: 0cm; margin-bottom: 10pt; margin-left: 0cm; text-align: justify; \"><span style=\"line-height: 18px; font-family: 'Times New Roman', serif; font-size: 12pt; \"><font face=\"verdana,sans-serif\">Para o deputado, o Governo Federal est&aacute; cumprindo um importante papel no apoio aos munic&iacute;pios, principalmente com a libera&ccedil;&atilde;o de recursos para obras nas &aacute;reas de educa&ccedil;&atilde;o, sa&uacute;de e esporte. &ldquo;S&atilde;o a&ccedil;&otilde;es acertadas, que acontecem em &aacute;reas vitais para a melhoria da qualidade de vida das comunidades&rdquo;, disse Zeca Dirceu, vice-l&iacute;der do PT na C&acirc;mara dos Deputados.<\/font><\/span><\/div>\n<div class=\"MsoNormal\" style=\"font-family: arial, sans-serif; font-size: 13px; margin-top: 0cm; margin-right: 0cm; margin-bottom: 10pt; margin-left: 0cm; text-align: justify; \">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>As prefeituras de Terra Boa e Moreira Sales, na regi\u00e3o Noroeste do Estado, receberam esta semana o pagamento das primeiras parcelas de conv\u00eanios referentes a obras federais que est\u00e3o sendo realizadas nos munic\u00edpios. Nas duas cidades est\u00e3o sendo constru\u00eddas creches que integram o Programa Proinf\u00e2ncia, do Governo Federal.<\/p>\n","protected":false},"author":1,"featured_media":28529,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6815],"class_list":["post-28530","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-noroeste-verbas"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/28530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=28530"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/28530\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/28529"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=28530"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=28530"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=28530"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}