{"id":28492,"date":"2011-09-05T00:00:00","date_gmt":"2011-09-05T03:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/cruzeiro-do-oeste-homenageia-miguel-kfouri\/"},"modified":"2011-09-05T00:00:00","modified_gmt":"2011-09-05T03:00:00","slug":"cruzeiro-do-oeste-homenageia-miguel-kfouri","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/cruzeiro-do-oeste-homenageia-miguel-kfouri\/","title":{"rendered":"Cruzeiro do Oeste homenageia Miguel Kfouri"},"content":{"rendered":"<p><span class=\"Apple-style-span\" style=\"font-family: 'Trebuchet MS', ARIAL; \">A C&acirc;mara de Vereadores de Cruzeiro do Oeste promoveu na noite desta quinta-feira uma das sess&otilde;es solenes mais emocionantes dos &uacute;ltimos anos. Na oportunidade, foi entregue o t&iacute;tulo de Cidad&atilde;o Honor&aacute;rio da cidade ao presidente do Tribunal de Justi&ccedil;a do Paran&aacute;, Miguel Kfouri Neto, um filho leg&iacute;timo da cidade. Ele viveu at&eacute; a adolesc&ecirc;ncia em Cruzeiro do Oeste, onde tamb&eacute;m iniciou os estudos e disse que ganhou nesta semana a sua verdadeira certid&atilde;o de nascimento. &ldquo;Cruzeiro do Oeste nunca se afastou da minha hist&oacute;ria&rdquo;, disse.&nbsp;<br \/>\nA sugest&atilde;o de homenagear o desembargador com a cidadania honor&aacute;ria foi feita pelo prefeito Valter Pereira da Rocha e recebeu aprova&ccedil;&atilde;o un&acirc;nime do Poder Legislativo. Ela se justifica principalmente pelo apre&ccedil;o que o homenageado tem pela cidade, que consta no seu curr&iacute;culo e na sua biografia, apesar de ele ser natural do Mato Grosso do Sul. Kfouri Neto, junto com sua fam&iacute;lia, residiu em Cruzeiro do Oeste dos tr&ecirc;s anos de idade at&eacute; a adolesc&ecirc;ncia e fala da cidade como sua terra-natal.&nbsp;<br \/>\nO t&iacute;tulo foi entregue pelo prefeito Valter Pereira da Rocha, o Valtinho, e o presidente da C&acirc;mara Municipal, Carlos Roberto Alegria, ao lado dos demais vereadores e tamb&eacute;m das ju&iacute;zas de Direito da comarca local, Roseli Maria Gueller Barcelos e Josiane P. Borges, a promotora de justi&ccedil;a local, Nadir Em&iacute;lia de Melo e o presidente da Ordem dos Advogados do Brasil (OAB), em Cruzeiro do Oeste, Carlos Roberto Jaquimil. Tamb&eacute;m estiveram na mesa principal o prefeito de Tapejara, Osvaldo Souza e o deputado estadual Jonas Guimar&atilde;es.&nbsp;<br \/>\nO prefeito Valtinho destacou as qualidades do homenageado e disse que o t&iacute;tulo de cidad&atilde;o &eacute; uma forma de a comunidade local agradecer Miguel Kfouri, que era conhecido na cidade como &ldquo;Miguelzinho&rdquo;. &rdquo;. &ldquo;&Eacute; uma homenagem mais do que justa e &eacute; grande a emo&ccedil;&atilde;o de receber o Miguelzinho, hoje presidente do TJ-PR, em Cruzeiro do Oeste, principalmente, num dia de homenagem&rdquo;, destacou o prefeito.&nbsp;<br \/>\nPara falar da hist&oacute;ria do homenageado fez uso da palavra o juiz de Direito aposentado, Jos&eacute; Mauro Flores, outro filho da cidade e amigo de inf&acirc;ncia de Kfouri. Ele destacou a sabedoria que faz parte da vida de Miguel Kfouri. &ldquo;Uma sabedoria semelhante a que Deus concedeu ao rei Salom&atilde;o&rdquo;. Ele lembrou momentos da inf&acirc;ncia do homenageado. As boas, como as brincadeiras na areia da rua Peabiru. E as ruins, como o inc&ecirc;ndio que destruiu um quarteir&atilde;o inteiro, onde hoje fica o Banco do Brasil e na &eacute;poca, na outra esquina, ficava a casa onde morava Miguel Kfouri com a m&atilde;e Solanger Garcia de Oliveira Kfouri, hoje uma advogada de 86 anos. Jos&eacute; Mauro destacou ainda a &eacute;tica e compet&ecirc;ncia que permeiam a vida do homenageado.&nbsp;<br \/>\nKfouri agradece<br \/>\nAo receber a homenagem, Miguel Kfouri agradeceu toda a comunidade e, principalmente, as pessoas que fizeram parte da sua vida. Citou as primeiras professoras, entre elas, Diva, Ruth, Hort&ecirc;ncia e Selfa, al&eacute;m de colegas da inf&acirc;ncia que hoje atuam em v&aacute;rias &aacute;reas e outros que j&aacute; faleceram. Falou das tardes de matin&ecirc;s no Cine Cruzeiro, das entregas de roupas para a m&atilde;e que era costureira, das brincadeiras e do aprendizado. &ldquo;Foi aqui que aprendi a gostar de ler e estudar e devo isso &agrave; minha m&atilde;e e professoras. Passei aqui uma inf&acirc;ncia feliz e jamais esquecerei&rdquo;.&nbsp;<br \/>\nMiguel Kfouri policial militar, bombeiro e professor universit&aacute;rio. Entrou para a Magistratura em 1984 e desde fevereiro passado preside o TJ.&nbsp;<br \/>\nOutras autoridades<br \/>\nTamb&eacute;m estiveram no evento o desembargador Julizar Barbosa, do TJ de Mato Grosso do Sul, o juiz auxiliar do TJ-PR, Frederico Mendes J&uacute;nior, al&eacute;m de ju&iacute;zes de Campo Mour&atilde;o, Umuarama e outras cidades.&nbsp;<br \/>\n&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>NOVO FORUM E VEP<\/p>\n<p><\/span><span class=\"Apple-style-span\" style=\"font-family: 'Trebuchet MS', ARIAL; \">Um dos momentos mais importantes e aplaudidos do discurso do desembargador foi quando ele lembrou a constru&ccedil;&atilde;o do novo F&oacute;rum de Cruzeiro do Oeste, prometendo voltar &agrave; cidade para a inaugura&ccedil;&atilde;o, em breve, e, em seguida, garantiu que o munic&iacute;pio ganhar&aacute; a Vara de Execu&ccedil;&otilde;es Penais (VEP), reivindica&ccedil;&atilde;o que est&aacute; entre as mais defendidas nos &uacute;ltimos meses pela comunidade. A instala&ccedil;&atilde;o da VEP se justifica principalmente pela constru&ccedil;&atilde;o da penitenci&aacute;ria, que dever&aacute; entrar em funcionamento no ano que vem. &ldquo;Vamos instalar essa VEP aqui em Cruzeiro&rdquo;, assegurou Kfouri Neto. O prefeito Valter Rocha classificou como &ldquo;uma honra&rdquo; a honraria prestada ao presidente do Tribunal de Justi&ccedil;a do Paran&aacute;. &ldquo;&Eacute; um orgulho para a nossa cidade&rdquo;, disse.<\/p>\n<p><\/span><span class=\"Apple-style-span\" style=\"font-family: 'Trebuchet MS', ARIAL; \">Fonte:<\/span><span class=\"Apple-style-span\" style=\"font-family: 'Trebuchet MS', ARIAL; \">&nbsp;<\/span><a href=\"http:\/\/www.ilustrado.com.br\/2011\/ExibeNoticia.aspx?Not=Cruzeiro%20do%20Oeste%20homenageia%20Miguel%20Kfouri&amp;NotID=9630\">http:\/\/www.ilustrado.com.br\/2011\/ExibeNoticia.aspx?Not=Cruzeiro%20do%20Oeste%20homenageia%20Miguel%20Kfouri&amp;NotID=9630<\/a><span class=\"Apple-style-span\" style=\"font-family: 'Trebuchet MS', ARIAL; \"><\/p>\n<p>\n&nbsp;<br \/>\n&nbsp;<\/p>\n<p><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara de Vereadores de Cruzeiro do Oeste promoveu na noite desta quinta-feira uma das sess\u00f5es solenes mais emocionantes dos \u00faltimos anos. Na oportunidade, foi entregue o t\u00edtulo de Cidad\u00e3o Honor\u00e1rio da cidade ao presidente do Tribunal de Justi\u00e7a do Paran\u00e1, Miguel Kfouri Neto, um filho leg\u00edtimo da cidade. Ele viveu at\u00e9 a adolesc\u00eancia em Cruzeiro do Oeste, onde tamb\u00e9m iniciou os estudos e disse que ganhou nesta semana a sua verdadeira certid\u00e3o de nascimento. \u201cCruzeiro do Oeste nunca se afastou da minha hist\u00f3ria\u201d, disse.<br \/>\nA sugest\u00e3o de homenagear o desembargador com a cidadania honor\u00e1ria foi feita pelo prefeito Valter Pereira da Rocha e recebeu aprova\u00e7\u00e3o un\u00e2nime do Poder Legislativo.<\/p>\n","protected":false},"author":1,"featured_media":28491,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6811],"class_list":["post-28492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-cruzeiro-do-oeste-cidadao"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/28492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=28492"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/28492\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/28491"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=28492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=28492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=28492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}