{"id":28380,"date":"2011-09-13T00:00:00","date_gmt":"2011-09-13T03:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/governo-vai-garantir-internet-de-qualidade-para-a-populacao\/"},"modified":"2011-09-13T00:00:00","modified_gmt":"2011-09-13T03:00:00","slug":"governo-vai-garantir-internet-de-qualidade-para-a-populacao","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/governo-vai-garantir-internet-de-qualidade-para-a-populacao\/","title":{"rendered":"Governo vai garantir internet de qualidade para a popula\u00e7\u00e3o"},"content":{"rendered":"<p>&nbsp;<span>&nbsp;<\/span>O ministro das Comunica&ccedil;&otilde;es Paulo Bernardo anunciou nesta segunda-feira, 12, que a medida provis&oacute;ria que ir&aacute; isentar tributos de equipamentos da Banda Larga no Brasil, sai esta semana. Ser&atilde;o investidos cerca de 20 bilh&otilde;es de reais para ampliar a rede de alta velocidade no pa&iacute;s, o in&iacute;cio das opera&ccedil;&otilde;es foi projetado para o pr&oacute;ximo ano.<\/p>\n<p class=\"MsoNormal\" style=\"text-align:justify\">Para o deputado Zeca Dirceu o pa&iacute;s avan&ccedil;a e se projeta quando os recursos chegam com igualdade. &ldquo;A melhoria na qualidade da internet, antes dos grandes eventos que o pa&iacute;s se prepara para receber, &eacute; um &oacute;timo sinal de que os projetos avan&ccedil;am e chegam com precis&atilde;o para o Brasil&rdquo;, explicou o deputado.<\/p>\n<p class=\"MsoNormal\" style=\"text-align:justify\">Os impostos que ser&atilde;o isentos para os equipamentos produzidos no pa&iacute;s s&atilde;o: PIS\/Pasep (Programa de Integra&ccedil;&atilde;o Social e Programa de Forma&ccedil;&atilde;o do Patrim&ocirc;nio do Servidor P&uacute;blico) e Cofins (Contribui&ccedil;&atilde;o para o Financiamento da Seguridade Social) , conforme o Processo Produtivo B&aacute;sico (PPB) e tamb&eacute;m para aqueles com tecnologia nacional.<\/p>\n<p class=\"MsoNormal\" style=\"text-align:justify\">A ren&uacute;ncia fiscal projetada para o per&iacute;odo 2012 a 2016 ficar&aacute; em R$ 4 bilh&otilde;es. O Programa Nacional de Banda Larga quer massificar o acesso &agrave; internet, para que todos tenham acesso ao conhecimento e tecnologia.<\/p>\n<p class=\"MsoNormal\" style=\"text-align:justify\">O ministro Paulo Bernardo tamb&eacute;m adiantou que a presidenta Dilma Rousseff avalizou a libera&ccedil;&atilde;o de mais R$ 200 milh&otilde;es do or&ccedil;amento da Telebr&aacute;s. O recurso dever&aacute; ser utilizado para garantir a infraestrutura de rede de banda larga que vai atender &agrave;s 12 cidades-sede da Copa do Mundo de 2014.<\/p>\n<p>Acompanhe a reportagem, no &iacute;cone abaixo.<br \/>\n<o:p><\/o:p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O ministro das Comunica\u00e7\u00f5es Paulo Bernardo anunciou nesta segunda-feira, 12, que a medida provis\u00f3ria que ir\u00e1 isentar tributos de equipamentos da Banda Larga no Brasil, sai esta semana. Ser\u00e3o investidos cerca de 20 bilh\u00f5es de reais para ampliar a rede de alta velocidade no pa\u00eds, o in\u00edcio das opera\u00e7\u00f5es foi projetado para o pr\u00f3ximo ano.<br \/>\nPara o deputado Zeca Dirceu o pa\u00eds avan\u00e7a e se projeta quando os recursos chegam com igualdade. \u201cA melhoria na qualidade da internet, antes dos grandes eventos que o pa\u00eds se prepara para receber, \u00e9 um \u00f3timo sinal de que os projetos avan\u00e7am e chegam com precis\u00e3o para o Brasil\u201d, explicou o deputado. Acompanhe a reportagem, no \u00edcone abaixo.<\/p>\n","protected":false},"author":1,"featured_media":28379,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6779],"class_list":["post-28380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-internet-governo"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/28380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=28380"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/28380\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/28379"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=28380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=28380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=28380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}