{"id":28314,"date":"2011-09-16T00:00:00","date_gmt":"2011-09-16T03:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/altonia-vai-escolher-amanha-a-rainha-do-rodeio-2011-3\/"},"modified":"2011-09-16T00:00:00","modified_gmt":"2011-09-16T03:00:00","slug":"altonia-vai-escolher-amanha-a-rainha-do-rodeio-2011-3","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/altonia-vai-escolher-amanha-a-rainha-do-rodeio-2011-3\/","title":{"rendered":"Alt\u00f4nia vai escolher amanh\u00e3 a rainha do rodeio 2011"},"content":{"rendered":"<p><span class=\"Apple-style-span\" style=\"font-family: 'Trebuchet MS', ARIAL; \">&nbsp;Ser&aacute; neste s&aacute;bado, a escolha da rainha e princesa da 21&ordf; Festa do Pe&atilde;o de Boiadeiro, Expo Alt&ocirc;nia 2011. Tamb&eacute;m haver&aacute; show com a dupla Brenno Reis e Marco Viola e um grande p&uacute;blico &eacute; esperado no pavilh&atilde;o de eventos da Sociedade Rural de Alt&ocirc;nia.<\/p>\n<p>Na passarela seis belas meninas estar&atilde;o esbanjando charme para todos os jurados e p&uacute;blico presente. O evento conta com a parceria da Radio Abdallah, Mega Eventos, apoio da Prefeitura de Alt&ocirc;nia, C&acirc;mara de Vereadores, Bulls Champions, Nistin Country, O Botic&aacute;rio, Sal&atilde;o Visualit, Alternativa Cal&ccedil;ados, Radical Click, Cupido Flores e Wendy Almeida e participa&ccedil;&atilde;o especial da Miss Paran&aacute;, Gabriela Pereira e a Mini Miss Paran&aacute;, Julia Vitoria Merotti.&nbsp;<br \/>\nO concurso &eacute; realizado pela SRA, representada pelo presidente Wagner Kiyoshi da Silva conta com o apoio para coordena&ccedil;&atilde;o do evento de Aline Rom&atilde;o, auxiliada por Jos&eacute; M. Rom&atilde;o e Marcos Cracco. Os ingressos para a Escolha da Rainha do Rodeio est&atilde;o &agrave; venda na Designer Modas, Wayliki Sorvetes, Farm&aacute;cia Modelo e Radio Abdallah.&nbsp;<br \/>\nPrograma&ccedil;&atilde;o da festa<\/p>\n<p>A diretoria da SRA j&aacute; definiu os shows que ir&atilde;o abrilhantar as noites dos dias 08 a 11 de dezembro pr&oacute;ximo na Expo Alt&ocirc;nia 2011. No dia 9, a dupla Thaeme e Thiago, No s&aacute;bado, dia 10, a anima&ccedil;&atilde;o ficar&aacute; por conta da dupla Humberto e Ronaldo e no domingo, al&eacute;m do show pirot&eacute;cnico, ser&aacute; a vez da dupla Felipe e Falc&atilde;o. Todas as noites haver&aacute; montaria, barrac&otilde;es de exposi&ccedil;&atilde;o, pra&ccedil;a de alimenta&ccedil;&atilde;o e parque de divers&otilde;es.<br \/>\nA 21&ordf; Festa do Pe&atilde;o de Boiadeiro, Expo Alt&ocirc;nia 2011 conta com o apoio da Prefeitura e C&acirc;mara de Vereadores.&nbsp;<\/p>\n<p>Fonte: Umuarama Ilustrado<br type=\"_moz\" \/><br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 neste s\u00e1bado, a escolha da rainha e princesa da 21\u00aa Festa do Pe\u00e3o de Boiadeiro, Expo Alt\u00f4nia 2011. Tamb\u00e9m haver\u00e1 show com a dupla Brenno Reis e Marco Viola e um grande p\u00fablico \u00e9 esperado no pavilh\u00e3o de eventos da Sociedade Rural de Alt\u00f4nia.<\/p>\n","protected":false},"author":1,"featured_media":28313,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6756],"class_list":["post-28314","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-altonia-evento"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/28314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=28314"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/28314\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/28313"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=28314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=28314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=28314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}