{"id":28266,"date":"2011-09-17T00:00:00","date_gmt":"2011-09-17T03:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/nutriphos-reinaugura-laboratorio-homeopatico-animal-em-umuarama\/"},"modified":"2011-09-17T00:00:00","modified_gmt":"2011-09-17T03:00:00","slug":"nutriphos-reinaugura-laboratorio-homeopatico-animal-em-umuarama","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/nutriphos-reinaugura-laboratorio-homeopatico-animal-em-umuarama\/","title":{"rendered":"Nutriph\u00f3s reinaugura laborat\u00f3rio homeop\u00e1tico animal, em Umuarama"},"content":{"rendered":"<p>&nbsp;Reinaugurado na tarde de sexta-feira, 16, em Umuarama, o laborat&oacute;rio homeop&aacute;tico de uma das mais conceituadas empresas de homeopatia veterin&aacute;ria do pa&iacute;s, a Nutriph&oacute;s. Desde 1995, no estado do Paran&aacute;, a empresa inova seu espa&ccedil;o f&iacute;sico e oferece ainda mais servi&ccedil;os e produtos de origem animal.<\/p>\n<p class=\"MsoNormal\" style=\"text-align:justify\">A cerim&ocirc;nia aconteceu na sede da empresa e contou com a presen&ccedil;a de autoridades locais, funcion&aacute;rios, representantes religiosos e pol&iacute;ticos. A equipe do deputado federal Zeca Dirceu esteve presente, representada pela coordenadora de Umuarama, Let&iacute;cia D&rsquo;Avila.<\/p>\n<p class=\"MsoNormal\" style=\"text-align:justify\">A miss&atilde;o da empresa &eacute; atuar em parceria com os produtores rurais, fornecendo produtos de qualidade que elevem a produ&ccedil;&atilde;o e lucratividade, agregando lucro a empresa rural.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\" style=\"text-align:justify\"><span>&nbsp;<\/span><b>Sa&uacute;de Animal<\/b> &#8211; A Homeopatia Veterin&aacute;ria &eacute; uma especializa&ccedil;&atilde;o da medicina Veterin&aacute;ria, aceita em todo territ&oacute;rio nacional, e exige do veterin&aacute;rio uma p&oacute;s-gradua&ccedil;&atilde;o atrav&eacute;s de cursos de especializa&ccedil;&atilde;o em Homeopatia, com atividades te&oacute;ricas e pr&aacute;ticas.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\" style=\"text-align:justify\">Considerada uma t&eacute;cnica terap&ecirc;utica, a Homeopatia foi difundida em todo o mundo, tanto para tratamento humano, quanto para o tratamento animal, e mant&eacute;m uma for&ccedil;a muito grande no Brasil. Ela &eacute; respons&aacute;vel por novos rumos nos conceitos de cria&ccedil;&atilde;o e manuten&ccedil;&atilde;o da sa&uacute;de e bem estar dos animais, e que desde seu in&iacute;cio tem assumido o papel importante para os animais por serem tratados de maneira individualizada, assim como o m&eacute;dico homeopata aborda o tratamento para o homem.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\" style=\"text-align:justify\">Vale ressaltar que a Homeopatia possui entre muitas vantagens, a utiliza&ccedil;&atilde;o dos medicamentos homeop&aacute;ticos na cria&ccedil;&atilde;o de animais de produ&ccedil;&atilde;o, de uma forma racional, tratando e mantendo a sa&uacute;de destes, sem deixar posteriores res&iacute;duos nos alimentos deles derivados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reinaugurado na tarde de sexta-feira, 16, em Umuarama, o laborat\u00f3rio homeop\u00e1tico de uma das mais conceituadas empresas de homeopatia veterin\u00e1ria do pa\u00eds, a Nutriph\u00f3s. A cerim\u00f4nia aconteceu na sede da empresa e contou com a presen\u00e7a de autoridades locais, funcion\u00e1rios, representantes religiosos e pol\u00edticos. A equipe do deputado federal Zeca Dirceu esteve presente, representada pela coordenadora de Umuarama, Let\u00edcia D\u2019Avila.<\/p>\n","protected":false},"author":1,"featured_media":28265,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6742],"class_list":["post-28266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-laboratorio-homeopatico-animal-umuarama"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/28266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=28266"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/28266\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/28265"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=28266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=28266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=28266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}