{"id":28232,"date":"2011-09-20T00:00:00","date_gmt":"2011-09-20T03:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/a-verdade-doa-a-quem-doer-por-zeca-dirceu\/"},"modified":"2011-09-20T00:00:00","modified_gmt":"2011-09-20T03:00:00","slug":"a-verdade-doa-a-quem-doer-por-zeca-dirceu","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/a-verdade-doa-a-quem-doer-por-zeca-dirceu\/","title":{"rendered":"A verdade doa a quem doer, por Zeca Dirceu"},"content":{"rendered":"<p>&nbsp;&ldquo;O que despoja a v&iacute;tima &eacute; o sil&ecirc;ncio&rdquo; &ndash; Jon Sobrino, sacerdote e te&oacute;logo espanhol<\/p>\n<p class=\"MsoNormal\"><o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Apesar dos avan&ccedil;os democr&aacute;ticos, algumas cicatrizes deixaram estampadas as marcas de uma a&ccedil;&atilde;o desumana e cruel: a tortura, a morte e o desaparecimento de centenas de brasileiros, afirma Zeca Dirceu<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Nos pr&oacute;ximos dias, a C&acirc;mara dos Deputados deve votar o projeto de lei que cria a Comiss&atilde;o Nacional da Verdade. Enviado pelo ent&atilde;o presidente Luiz In&aacute;cio Lula da Silva, em 2010, o projeto prev&ecirc; a apura&ccedil;&atilde;o das viola&ccedil;&otilde;es aos direitos humanos no per&iacute;odo compreendido entre 1946 e 1988 &ndash; hiato entre as duas &uacute;ltimas Constitui&ccedil;&otilde;es do Pa&iacute;s. A estrat&eacute;gia &eacute; aprovar, tanto na C&acirc;mara como no Senado, em regime de urg&ecirc;ncia urgent&iacute;ssima, ou seja, sem debater nas Comiss&otilde;es Parlamentares. A discuss&atilde;o do tema mostra que o Brasil evoluiu &ndash; e muito &ndash; nos &uacute;ltimos anos. E com ele, suas resolu&ccedil;&otilde;es.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">O tema &eacute; delicado. Envolve um per&iacute;odo da vida nacional, principalmente entre 1964 e 1979, quando foi promulgada a Lei da Anistia, em que o Pa&iacute;s viveu submerso numa ditadura militar que se caracterizou pela aus&ecirc;ncia de democracia, pela supress&atilde;o dos direitos constitucionais, da censura, persegui&ccedil;&atilde;o pol&iacute;tica e repress&atilde;o aos que eram contr&aacute;rios ao regime. A democracia plena s&oacute; ressurgiu em 1985 com a ru&iacute;na da ditadura. Seu efeito mais imediato foi a elabora&ccedil;&atilde;o de uma nova Carta Magna em 1988. Apesar dos avan&ccedil;os democr&aacute;ticos, algumas cicatrizes deixaram estampadas as marcas de uma a&ccedil;&atilde;o desumana e cruel: a tortura, a morte e o desaparecimento de centenas de brasileiros. Ainda hoje n&atilde;o se sabe o n&uacute;mero exato dessas v&iacute;timas, mas certamente somam-se as centenas.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">A Comiss&atilde;o da Verdade busca apenas reparar esses erros. N&atilde;o h&aacute; qualquer sentido de vingan&ccedil;a, de arb&iacute;trio ou de ca&ccedil;a &agrave;s bruxas. Ali&aacute;s, se assim fosse, estar&iacute;amos cometendo o mesmo erro &agrave;s avessas. Mas as fam&iacute;lias e principalmente as v&iacute;timas do arb&iacute;trio merecem respeito. Segundo a psicanalista Maria Rita Kehl &ldquo;o ressentimento n&atilde;o abate aqueles que foram derrotados na luta e no enfrentamento com o opressor e sim os que recuaram sem lutar e perdoaram sem exigir repara&ccedil;&atilde;o&rdquo;. &Eacute; justamente isso que a Comiss&atilde;o se prop&otilde;e fazer a partir de agora.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">A experi&ecirc;ncia brasileira n&atilde;o &eacute; nenhuma novidade. Um dos exemplos cl&aacute;ssicos deu-se na &Aacute;frica do Sul ap&oacute;s a queda do apartheid &ndash; o regime de segrega&ccedil;&atilde;o racial que vigorou entre 1948 e 1988 e foi definitivamente enterrado com a elei&ccedil;&atilde;o de Nelson Mandela. A &uacute;nica alternativa para restabelecer a verdade era conhecer os fatos e ouvir dos pr&oacute;prios part&iacute;cipes suas vers&otilde;es.<span>&nbsp; <\/span>Na Alemanha, ap&oacute;s a queda do Muro de Berlim e a reunifica&ccedil;&atilde;o dos povos, tamb&eacute;m foi necess&aacute;rio reabrir os arquivos da policia secreta.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Por certo foram cometidos excessos de ambos os lados. No entanto, nada pode ser mais cruel e torturante diante de um trauma social que o sil&ecirc;ncio dos que se dizem vencedores. Restam os filhos mortos de pais vivos; os filhos vivos de pais que nunca se fizeram presentes. &Eacute; preciso que a verdade venha &agrave; tona para quem sabe amenizar o sofrimento dos que insistem em conhec&ecirc;-la.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">A responsabilidade do Congresso Nacional &eacute; da maior relev&acirc;ncia. Certamente haver&aacute; controv&eacute;rsias e grandes obst&aacute;culos at&eacute; a conclus&atilde;o dos resultados da Comiss&atilde;o cuja fun&ccedil;&atilde;o n&atilde;o &eacute; julgar, mas coordenar um processo que devolva &agrave;s fam&iacute;lias nada mais do que a verdade. Ou como diria o poeta Thiago de Mello, &ldquo;aos que n&atilde;o sabem conv&ecirc;m contar; aos que se esquecem, conv&ecirc;m lembrar&rdquo;.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\"><o:p>&nbsp;<\/o:p><\/p>\n<p class=\"MsoNormal\">*Zeca Dirceu &eacute; deputado federal pelo PT<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\"><o:p>&nbsp;<\/o:p><\/p>\n<p class=\"MsoNormal\"><o:p>&nbsp;<\/o:p><\/p>\n<h1 class=\"tit-arial padding-bottom\" style=\"margin-top: 20px; margin-right: 0px; margin-bottom: 0px; margin-left: 0px; padding-top: 0px; padding-right: 0px; padding-bottom: 10px; padding-left: 0px; border-top-width: 0px; border-right-width: 0px; border-bottom-width: 0px; border-left-width: 0px; border-style: initial; border-color: initial; outline-width: 0px; outline-style: initial; outline-color: initial; font-size: 30px; vertical-align: baseline; background-image: initial; background-attachment: initial; background-origin: initial; background-clip: initial; background-color: transparent; font-weight: bold; font-family: Arial, Helvetica, sans-serif; color: rgb(51, 51, 51); text-decoration: none; background-position: initial initial; background-repeat: initial initial; \">&nbsp;<\/h1>\n","protected":false},"excerpt":{"rendered":"<p>No dia 19 de setembro a conceituada Revista Carta Capital publicou artigo de minha autoria. O conte\u00fado pode ser acompanhado na edi\u00e7\u00e3o online da revista pelo endere\u00e7o eletr\u00f4nico http:\/\/www.cartacapital.com.br\/politica\/a-verdade-doa-a-quem-doer. Agrade\u00e7o aos editores da Revista pela divulga\u00e7\u00e3o.<\/p>\n<p>Acompanhe na \u00edntegra a publica\u00e7\u00e3o.<\/p>\n","protected":false},"author":1,"featured_media":28231,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6675],"class_list":["post-28232","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-a-verdade-doa-a-quem-doer"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/28232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=28232"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/28232\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/28231"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=28232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=28232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=28232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}