{"id":28142,"date":"2011-09-26T00:00:00","date_gmt":"2011-09-26T03:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/luiziana-comemora-24-anos\/"},"modified":"2011-09-26T00:00:00","modified_gmt":"2011-09-26T03:00:00","slug":"luiziana-comemora-24-anos","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/luiziana-comemora-24-anos\/","title":{"rendered":"Luiziana comemora 24 anos"},"content":{"rendered":"<p>&nbsp;O munic&iacute;pio de Luiziana comemorou 24 anos, neste domingo, 25. Para celebrar a data a Expoluz, na sua quinta edi&ccedil;&atilde;o, proporcionou divers&atilde;o e descontra&ccedil;&atilde;o, com tr&ecirc;s dias de festa.<\/p>\n<p class=\"MsoNormal\">Na &nbsp;5&ordf; Expoluz de Luiziana, o p&uacute;blico p&ocirc;de participar de v&aacute;rias atra&ccedil;&otilde;es como parque de divers&otilde;es para o lazer das crian&ccedil;as, pra&ccedil;a de alimenta&ccedil;&atilde;o, atra&ccedil;&otilde;es musicais, rodeios, cavalgada, encontro de trilheiros, e almo&ccedil;o com o prato t&iacute;pico &ldquo;Boi na Brasa&rdquo;.<\/p>\n<p class=\"MsoNormal\">O deputado federal Zeca Dirceu cumprimenta os moradores de Luiziana. Acompanhe a mensagem no &iacute;cone abaixo.&nbsp;<o:p><\/o:p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O munic\u00edpio de Luiziana comemorou 24 anos, neste domingo, 25. Para celebrar a data a Expoluz, na sua quinta edi\u00e7\u00e3o, proporcionou divers\u00e3o e descontra\u00e7\u00e3o, com tr\u00eas dias de festa. <\/p>\n<p>O deputado federal Zeca Dirceu cumprimenta os moradores de Luiziana. Acompanhe a mensagem no \u00edcone abaixo.<\/p>\n","protected":false},"author":1,"featured_media":28141,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6701],"class_list":["post-28142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-luiziana-comemora-24-anos"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/28142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=28142"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/28142\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/28141"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=28142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=28142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=28142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}