{"id":27992,"date":"2011-10-03T00:00:00","date_gmt":"2011-10-03T03:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/sanepar-vai-investir-r-166-milhoes-do-pac-2-no-saneamento-de-paranavai\/"},"modified":"2011-10-03T00:00:00","modified_gmt":"2011-10-03T03:00:00","slug":"sanepar-vai-investir-r-166-milhoes-do-pac-2-no-saneamento-de-paranavai","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/sanepar-vai-investir-r-166-milhoes-do-pac-2-no-saneamento-de-paranavai\/","title":{"rendered":"Sanepar vai investir R$ 16,6 milh\u00f5es do PAC 2 no saneamento de Paranava\u00ed"},"content":{"rendered":"<p>&nbsp;A Companhia de Saneamento do Paran&aacute; (Sanepar) recebeu a confirma&ccedil;&atilde;o, na semana passada, de que o Banco Nacional de Desenvolvimento Econ&ocirc;mico e Social (BNDES) aprovou o financiamento de R$ 16,6 milh&otilde;es para obras de amplia&ccedil;&atilde;o e melhoria dos sistemas de abastecimento de &aacute;gua e de tratamento de esgoto na cidade de Paranava&iacute;. Os projetos integram o pacote de investimentos do Programa de Acelera&ccedil;&atilde;o do Crescimento (PAC) 2.<\/p>\n<p class=\"MsoNormal\"><o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">&ldquo;Fico feliz em saber que esta etapa do financiamento est&aacute; resolvida, porque h&aacute; bastante tempo venho reivindicando junto ao presidente da Sanepar, Fernando Ghignone, a realiza&ccedil;&atilde;o destas obras. Paranava&iacute; vai ser beneficiada com melhorias importantes, numa das &aacute;reas mais sens&iacute;veis para a sa&uacute;de dos cidad&atilde;os&rdquo;, afirmou o deputado federal Zeca Dirceu (PT-PR).<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Os investimentos da Sanepar ser&atilde;o feitos no Sistema de Abastecimento de &Aacute;gua (SAA), compreendendo esta&ccedil;&otilde;es subterr&acirc;neas, Esta&ccedil;&atilde;o de Tratamento de &Aacute;gua e substitui&ccedil;&atilde;o de adutora, com valor de R$ 3,4 milh&otilde;es. J&aacute; a amplia&ccedil;&atilde;o do Sistema de Esgotamento Sanit&aacute;rio, compreendendo rede coletora, liga&ccedil;&otilde;es, elevat&oacute;rias e Esta&ccedil;&otilde;es de Tratamento de Esgoto na Vila City e Vila Oper&aacute;ria, consumir&aacute; outros R$ 13,2 milh&otilde;es.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Os projetos de Paranava&iacute; estavam garantidos na pr&eacute;-sele&ccedil;&atilde;o do PAC 2 desde o ano passado. Com a confirma&ccedil;&atilde;o do financiamento das obras pelo BNDES, resta agora &agrave; estatal de saneamento comprovar sua capacidade de endividamento junto ao banco para que as obras possam ser iniciadas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Companhia de Saneamento do Paran\u00e1 (Sanepar) recebeu a confirma\u00e7\u00e3o, na semana passada, de que o Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES) aprovou o financiamento de R$ 16,6 milh\u00f5es para obras de amplia\u00e7\u00e3o e melhoria dos sistemas de abastecimento de \u00e1gua e de tratamento de esgoto na cidade de Paranava\u00ed. Os projetos integram o pacote de investimentos do Programa de Acelera\u00e7\u00e3o do Crescimento (PAC) 2.<\/p>\n","protected":false},"author":1,"featured_media":27991,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6640,6639],"class_list":["post-27992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-6-milhoes-do-pac-2-no-saneamento-de-paranavai","tag-sanepar-vai-investir-r-16"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=27992"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27992\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/27991"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=27992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=27992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=27992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}