{"id":27913,"date":"2011-10-06T00:00:00","date_gmt":"2011-10-06T03:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/zeca-destaca-aprovacao-popular-de-dilma-rousseff\/"},"modified":"2011-10-06T00:00:00","modified_gmt":"2011-10-06T03:00:00","slug":"zeca-destaca-aprovacao-popular-de-dilma-rousseff","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/zeca-destaca-aprovacao-popular-de-dilma-rousseff\/","title":{"rendered":"Zeca destaca aprova\u00e7\u00e3o popular de Dilma Rousseff"},"content":{"rendered":"<p class=\"MsoNormal\">A presidenta Dilma Roussef tem 71% de aprova&ccedil;&atilde;o pessoal da popula&ccedil;&atilde;o, segundo a pesquisa da Confedera&ccedil;&atilde;o Nacional da Ind&uacute;stria (CNI) encomendada ao Ibope e divulgada no dia 31 de setembro. Para o deputado federal Zeca Dirceu a pesquisa revela que a presidenta est&aacute; no caminho certo, e que os brasileiros sentem as melhoras na qualidade de vida. O deputado, que tamb&eacute;m &eacute; vice-l&iacute;der da bancada do PT no Congresso Nacional, falou sobre a coragem do Governo em come&ccedil;ar um programa de redu&ccedil;&atilde;o da taxa de juros, que &eacute; importante tamb&eacute;m para a exporta&ccedil;&atilde;o, em meio a uma crise mundial. &ldquo;O Brasil vive um grande momento e, n&atilde;o por acaso, que a presidenta tem essa aceita&ccedil;&atilde;o&rdquo; explicou o parlamentar.<\/p>\n<p class=\"MsoNormal\">Zeca tamb&eacute;m destacou seu trabalho e de seus companheiros. &ldquo;Estes 71%, que tem a presidenta Dilma, chega a ser superior a porcentagem do presidente Lula, em 2003. E isso nos enche de orgulho, n&oacute;s aqui defendendo a presidenta Dilma no Congresso Nacional, muitas vezes em embates muito duros provocados pela oposi&ccedil;&atilde;o, que tenta desestabilizar o Governo, que tenta obstruir, que tenta criar dificuldades para que leis, para que medidas sejam aprovadas no Congresso Nacional&rdquo; ressaltou o deputado. O parlamentar acrescentou, ainda, que a popula&ccedil;&atilde;o percebe que o pa&iacute;s mudou. O povo aprova a presidenta Dilma Rousseff.<span>&nbsp; <\/span>Ou&ccedil;a a reportagem na &iacute;ntegra, no &iacute;cone abaixo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A presidenta Dilma Roussef tem 71% de aprova\u00e7\u00e3o pessoal da popula\u00e7\u00e3o, segundo a pesquisa da Confedera\u00e7\u00e3o Nacional da Ind\u00fastria (CNI) encomendada ao Ibope e divulgada no dia 31 de setembro. Para o deputado federal Zeca Dirceu a pesquisa revela que a presidenta est\u00e1 no caminho certo, e que os brasileiros sentem as melhoras na qualidade de vida.Ou\u00e7a a reportagem na \u00edntegra, no \u00edcone abaixo.<\/p>\n","protected":false},"author":1,"featured_media":27912,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6602],"class_list":["post-27913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-zeca-destaca-aprovacao-popular-de-dilma-rousseff"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=27913"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27913\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/27912"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=27913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=27913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=27913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}