{"id":27909,"date":"2011-10-06T00:00:00","date_gmt":"2011-10-06T03:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/candidatos-do-enem-podem-tirar-duvidas-em-hotsite\/"},"modified":"2011-10-06T00:00:00","modified_gmt":"2011-10-06T03:00:00","slug":"candidatos-do-enem-podem-tirar-duvidas-em-hotsite","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/candidatos-do-enem-podem-tirar-duvidas-em-hotsite\/","title":{"rendered":"Candidatos do Enem podem tirar d\u00favidas em hotsite"},"content":{"rendered":"<p>&nbsp;<span class=\"Apple-style-span\" style=\"color: rgb(40, 49, 48); font-family: Arial, Helvetica, sans-serif; font-size: 13px; line-height: 17px; \">Est&aacute; no ar o&nbsp;<a class=\"external-link first-child last-child\" href=\"http:\/\/www.enem.inep.gov.br\/\" target=\"_blank\" style=\"margin-top: 0px; margin-right: 0px; margin-bottom: 0px; margin-left: 0px; padding-top: 0px; padding-right: 12px; padding-bottom: 0px; padding-left: 0px; border-top-width: 0px; border-right-width: 0px; border-bottom-width: 0px; border-left-width: 0px; border-style: initial; border-color: initial; outline-width: 0px; outline-style: initial; outline-color: initial; vertical-align: baseline; background-image: url(http:\/\/www.secom.gov.br\/portal_css\/Secom\/bg\/linkExterno.gif); background-attachment: initial; background-origin: initial; background-clip: initial; background-color: initial; color: rgb(23, 67, 155); text-decoration: underline; background-position: 100% 50%; background-repeat: no-repeat no-repeat; \">hotsite&nbsp;<\/a>desta edi&ccedil;&atilde;o do Exame Nacional do Ensino M&eacute;dio (Enem). L&aacute;, os inscritos podem tirar d&uacute;vidas e conferir locais de prova. O candidato saber&aacute; tamb&eacute;m quais documentos ser&atilde;o aceitos para a realiza&ccedil;&atilde;o do exame, os objetos que devem levar e aqueles que n&atilde;o ser&atilde;o permitidos. Ter&aacute; ainda informa&ccedil;&otilde;es sobre as provas de reda&ccedil;&atilde;o e de l&iacute;ngua estrangeira. &Eacute; poss&iacute;vel tamb&eacute;m conferir dicas para o estudante se programar e participar do processo com tranquilidade.<\/p>\n<p>A p&aacute;gina traz ainda acesso ao endere&ccedil;o onde o inscrito pode conferir o munic&iacute;pio no qual far&aacute; a prova e imprimir o cart&atilde;o de confirma&ccedil;&atilde;o de inscri&ccedil;&atilde;o. O candidato pode ainda assistir a um v&iacute;deo de tr&ecirc;s minutos com as principais orienta&ccedil;&otilde;es sobre o processo. O Enem ser&aacute; realizado em 1.599 munic&iacute;pios de todo o Brasil. Far&atilde;o as provas 5.366.780 pessoas, em 22 e 23 de outubro. Recomenda-se que os estudantes cheguem at&eacute; meio-dia ao local de prova. Os port&otilde;es de acesso ser&atilde;o fechados pontualmente &agrave;s 13h, hor&aacute;rio de Bras&iacute;lia.<\/p>\n<p>Fonte: Em Quest&atilde;o &#8211; Secom<br type=\"_moz\" \/><br \/>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e1 no ar o hotsite desta edi\u00e7\u00e3o do Exame Nacional do Ensino M\u00e9dio (Enem). L\u00e1, os inscritos podem tirar d\u00favidas e conferir locais de prova. O candidato saber\u00e1 tamb\u00e9m quais documentos ser\u00e3o aceitos para a realiza\u00e7\u00e3o do exame, os objetos que devem levar e aqueles que n\u00e3o ser\u00e3o permitidos. Ter\u00e1 ainda informa\u00e7\u00f5es sobre as provas de reda\u00e7\u00e3o e de l\u00edngua estrangeira. \u00c9 poss\u00edvel tamb\u00e9m conferir dicas para o estudante se programar e participar do processo com tranquilidade.<\/p>\n","protected":false},"author":1,"featured_media":27908,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6600],"class_list":["post-27909","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-candidatos-do-enem-podem-tirar-duvidas-em-hotsite"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=27909"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27909\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/27908"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=27909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=27909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=27909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}