{"id":27895,"date":"2011-10-09T00:00:00","date_gmt":"2011-10-09T03:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/fim-de-semana-de-agenda-movimentada-5\/"},"modified":"2011-10-09T00:00:00","modified_gmt":"2011-10-09T03:00:00","slug":"fim-de-semana-de-agenda-movimentada-5","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/fim-de-semana-de-agenda-movimentada-5\/","title":{"rendered":"Fim de semana de agenda movimentada"},"content":{"rendered":"<p>&nbsp;O fim de semana come&ccedil;ou cedo na regi&atilde;o noroeste. Logo na quinta-feira, muita movimenta&ccedil;&atilde;o com a reuni&atilde;o do partido (PT), no escrit&oacute;rio regional de Umuarama. Na seq&uuml;&ecirc;ncia visitei o munic&iacute;pio de Xambr&ecirc;, onde fui recepcionado por v&aacute;rios companheiros de partido.<\/p>\n<p class=\"MsoNormal\">Na sexta-feira, o primeiro compromisso foi em Cruzeiro do Oeste, no III Encontro Regional dos Profissionalizantes das Apaes. Em seguida acompanhei a inaugura&ccedil;&atilde;o da Unidade B&aacute;sica de Sa&uacute;de &#8211; UBS &#8211; no distrito S&atilde;o Silvestre, junto com prefeito Valtinho, de Cruzeiro do Oeste. Depois segui para Campo Mour&atilde;o. L&aacute; participei da abertura da 25&ordf; edi&ccedil;&atilde;o dos Jojups (Jogos da Juventude do Paran&aacute;), tamb&eacute;m visitei a TV Caraj&aacute;s. No domingo &agrave; tarde fui &agrave; Cidade Ga&uacute;cha.<\/p>\n<p class=\"MsoNormal\">Nesta segunda-feira,10, participo de um evento em Cianorte, depois retorno a Bras&iacute;lia, para mais uma semana de trabalho. Os detalhes das visitas voc&ecirc;s acompanham aqui no blog, no decorrer da semana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O fim de semana come\u00e7ou cedo na regi\u00e3o noroeste. Logo na quinta-feira, muita movimenta\u00e7\u00e3o com a reuni\u00e3o do partido (PT), no escrit\u00f3rio regional de Umuarama. Na seq\u00fc\u00eancia visitei o munic\u00edpio de Xambr\u00ea, onde fui recepcionado por v\u00e1rios companheiros de partido.<br \/>\nNa sexta-feira, o primeiro compromisso foi em Cruzeiro do Oeste, no III Encontro Regional dos Profissionalizantes das Apaes. Em seguida acompanhei a inaugura\u00e7\u00e3o da Unidade B\u00e1sica de Sa\u00fade &#8211; UBS &#8211; no distrito S\u00e3o Silvestre, junto com prefeito Valtinho, de Cruzeiro do Oeste. Depois segui para Campo Mour\u00e3o. L\u00e1 participei da abertura da 25\u00aa edi\u00e7\u00e3o dos Jojups (Jogos da Juventude do Paran\u00e1), tamb\u00e9m visitei a TV Caraj\u00e1s. No domingo \u00e0 tarde fui \u00e0 Cidade Ga\u00facha.<\/p>\n","protected":false},"author":1,"featured_media":27894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6595],"class_list":["post-27895","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-fim-de-semana-de-agenda-movimentada"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=27895"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27895\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/27894"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=27895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=27895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=27895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}