{"id":27725,"date":"2011-10-18T00:00:00","date_gmt":"2011-10-18T02:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/cadastro-nacional-registrara-areas-de-risco-para-prevenir-e-reduzir-impacto-das-chuvas\/"},"modified":"2011-10-18T00:00:00","modified_gmt":"2011-10-18T02:00:00","slug":"cadastro-nacional-registrara-areas-de-risco-para-prevenir-e-reduzir-impacto-das-chuvas","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/cadastro-nacional-registrara-areas-de-risco-para-prevenir-e-reduzir-impacto-das-chuvas\/","title":{"rendered":"Cadastro nacional registrar\u00e1 \u00e1reas de risco para prevenir e reduzir impacto das chuvas"},"content":{"rendered":"<p>&nbsp;Cidades com bairros em encostas que podem deslizar durante o per&iacute;odo das chuvas poder&atilde;o registrar essas &aacute;reas de risco num cadastro nacional, que ser&aacute; alimentado tamb&eacute;m pelos governos federal, estaduais e distrital. Al&eacute;m de identificar os locais onde pode haver escorregamentos, ser&atilde;o estabelecidas medidas a serem adotadas para a preven&ccedil;&atilde;o e redu&ccedil;&atilde;o de riscos, que contar&atilde;o com o apoio da Uni&atilde;o e governos estaduais, de acordo com justificativa da Medida Provis&oacute;ria (MP) 547, publicada no Di&aacute;rio .<\/p>\n<p class=\"MsoNormal\">A informa&ccedil;&atilde;o &eacute; importante para o funcionamento do Sistema de Monitoramento e Alertas de Desastres Naturais, pois, os alertas correm o risco de perda da credibilidade se forem baseados apenas em dados meteorol&oacute;gicos, sem dados precisos da geologia e da ocupa&ccedil;&atilde;o urbana, informa o ministro da Ci&ecirc;ncia, Tecnologia e Inova&ccedil;&atilde;o (MCTI), Aloizio Mercadante.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Levantamento preliminar, apresentado pelo governo federal em junho, aponta que h&aacute; 735 munic&iacute;pios brasileiros com pelo menos cinco &aacute;reas de riscos de deslizamento. As cidades s&atilde;o de Alagoas, Bahia, Esp&iacute;rito Santo, Minas Gerais, Paran&aacute;, Pernambuco, Rio de Janeiro, Santa Catarina e S&atilde;o Paulo. Em todos os estados, apenas 25 cidades (3,4%) disp&otilde;em de cartas geot&eacute;cnicas. Esses estudos ser&atilde;o obrigat&oacute;rios para as prefeituras que v&atilde;o constar do cadastro nacional e demarcam as &aacute;reas de risco. <o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Preven&ccedil;&atilde;o<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">De acordo com o Minist&eacute;rio das Cidades, esses munic&iacute;pios ter&atilde;o de elaborar as cartas geot&eacute;cnicas para que os futuros projetos de parcelamento do solo levem em conta a preven&ccedil;&atilde;o ao risco. As prefeituras dever&atilde;o tamb&eacute;m elaborar Planos de Expans&atilde;o Urbana, submetendo os projetos de parcelamento ao disposto nestes planos.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">A MP prev&ecirc; que ser&atilde;o mantidas as a&ccedil;&otilde;es de urbaniza&ccedil;&atilde;o de assentamentos prec&aacute;rios por meio de obras de seguran&ccedil;a em encostas, para reduzir riscos. E, quando houver necessidade de remo&ccedil;&atilde;o das fam&iacute;lias, dever&atilde;o ser reassentadas em local seguro, por programas habitacionais. O minist&eacute;rio informa que as &aacute;reas ainda n&atilde;o ocupadas e que podem escorregar ser&atilde;o monitoradas e fiscalizadas para evitar a ocupa&ccedil;&atilde;o.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Centro monitora riscos de desastres naturais <o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Criado em junho, o Centro de Monitoramento e Alertas de Desastres Naturais (Cemaden\/ MCTI) gerencia as informa&ccedil;&otilde;es emitidas por radares, pluvi&ocirc;metros e previs&otilde;es clim&aacute;ticas, por meio de um supercomputador &#8211; o Tup&atilde;, instalado na sede do Cemaden, em Cachoeira Paulista (SP). Durante quatro anos, per&iacute;odo de instala&ccedil;&atilde;o total do sistema de alerta, ser&atilde;o investidos R$ 250 milh&otilde;es. Atualmente, o trabalho para preven&ccedil;&atilde;o de escorregamentos &eacute; feito para as 25 cidades que t&ecirc;m cartas geot&eacute;cnicas prontas.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Os especialistas do Cemaden v&atilde;o trabalhar com previs&otilde;es de alta resolu&ccedil;&atilde;o e ainda com uma s&eacute;rie de equipamentos como radares meteorol&oacute;gicos e de an&aacute;lise de solo. <o:p><\/o:p><\/p>\n<p class=\"MsoNormal\"><o:p>&nbsp;Fonte: Em quest&atilde;o<\/p>\n<p class=\"MsoNormal\">Ou&ccedil;a a reportagem do deputado Zeca Dirceu sobre o assunto.<\/p>\n<p><\/o:p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cidades com bairros em encostas que podem deslizar durante o per\u00edodo das chuvas poder\u00e3o registrar essas \u00e1reas de risco num cadastro nacional, que ser\u00e1 alimentado tamb\u00e9m pelos governos federal, estaduais e distrital. Al\u00e9m de identificar os locais onde pode haver escorregamentos, ser\u00e3o estabelecidas medidas a serem adotadas para a preven\u00e7\u00e3o e redu\u00e7\u00e3o de riscos, que contar\u00e3o com o apoio da Uni\u00e3o e governos estaduais, de acordo com justificativa da Medida Provis\u00f3ria (MP) 547, publicada no Di\u00e1rio .Ou\u00e7a a reportagem do deputado Zeca Dirceu sobre o assunto.<\/p>\n","protected":false},"author":1,"featured_media":27724,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6530],"class_list":["post-27725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-cadastro-nacional-registrara-areas-de-risco-para-prevenir-e-reduzir-impacto-das-chuvas"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=27725"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27725\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/27724"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=27725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=27725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=27725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}