{"id":27505,"date":"2011-10-27T00:00:00","date_gmt":"2011-10-27T02:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/ministerio-das-cidades-repassa-r-68-mil-para-cruzeiro-do-oeste\/"},"modified":"2011-10-27T00:00:00","modified_gmt":"2011-10-27T02:00:00","slug":"ministerio-das-cidades-repassa-r-68-mil-para-cruzeiro-do-oeste","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/ministerio-das-cidades-repassa-r-68-mil-para-cruzeiro-do-oeste\/","title":{"rendered":"Minist\u00e9rio das Cidades repassa  R$ 68 mil para Cruzeiro do Oeste"},"content":{"rendered":"<p>&nbsp;A Prefeitura de Cruzeiro do Oeste recebeu do Minist&eacute;rio das Cidades, na semana passada, a segunda parcela do pagamento de obras de pavimenta&ccedil;&atilde;o, galerias e implanta&ccedil;&atilde;o de sem&aacute;foro. Os recursos, conquistados em Bras&iacute;lia por meio da articula&ccedil;&atilde;o do deputado federal Zeca Dirceu (PT-PR), somam R$ 68.668,60 e representam 10% do valor total do conv&ecirc;nio, estipulado em R$ 686.000,00.<\/p>\n<p class=\"MsoNormal\"><o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">&ldquo;&Eacute; mais uma luta que vencemos em Bras&iacute;lia. O pagamento destes recursos possibilita ao prefeito Valtinho dar sequ&ecirc;ncia em obras importantes para a cidade, beneficiando diretamente a popula&ccedil;&atilde;o de Cruzeiro do Oeste&rdquo;, afirma Zeca Dirceu, que foi prefeito do munic&iacute;pio entre 2005 e 2010.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">No dia 8 de julho deste ano, o Minist&eacute;rio das Cidades j&aacute; havia repassado ao munic&iacute;pio o pagamento da primeira parcela do conv&ecirc;nio, no valor de R$ 97.960,80. Com o pagamento deste m&ecirc;s, a Prefeitura j&aacute; recebeu R$ 166.629,40, o que representa quase 25% do valor total previsto para as obras.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">A medi&ccedil;&atilde;o mais recente, feita pela Caixa Econ&ocirc;mica Federal no in&iacute;cio de outubro, mostra que a obra est&aacute; 66,55% conclu&iacute;da. O conv&ecirc;nio prev&ecirc; a instala&ccedil;&atilde;o de dois sem&aacute;foros &ndash; obra j&aacute; conclu&iacute;da na esquina das ruas Peabiru e Paran&aacute; e na esquina da Rua Jo&atilde;o Ormindo de Resende com a Avenida Brasil &ndash; e tamb&eacute;m a instala&ccedil;&atilde;o de galerias de &aacute;guas pluviais em partes da Avenida Garibaldi e da Rua Paran&aacute;, com a posterior pavimenta&ccedil;&atilde;o dos trechos escavados.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\"><o:p>&nbsp;<\/o:p><\/p>\n<p class=\"MsoNormal\">Mais recursos<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Zeca Dirceu lembra que existem tratativas em Bras&iacute;lia para atrair muito mais verbas federais para Cruzeiro do Oeste. &ldquo;Estou atento e acompanhando de perto o andamento dos repasses para Cruzeiro do Oeste, n&atilde;o s&oacute; deste conv&ecirc;nio com o Minist&eacute;rio das Cidades, mas de outros recursos que estamos pleiteando, em parceria com o prefeito Valtinho, em diversos minist&eacute;rios&rdquo;, diz o parlamentar.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\"><o:p>&nbsp;<\/o:p>Por sua vez, o prefeito Valter Rocha, o Valtinho, destacou a import&acirc;ncia do pagamento do Minist&eacute;rio das Cidades para a sequ&ecirc;ncia das obras e agradeceu o empenho de Zeca Dirceu na defesa de verbas para o munic&iacute;pio. &ldquo;Esta parceria vitoriosa com o deputado Zeca tem trazido muitas melhorias para Cruzeiro do Oeste, e tenho certeza de que ele ainda vai nos proporcionar muitas alegrias como representante da cidade em Bras&iacute;lia&rdquo;, disse Valtinho.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\"><o:p>&nbsp;<\/o:p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Cruzeiro do Oeste recebeu do Minist\u00e9rio das Cidades, na semana passada, a segunda parcela do pagamento de obras de pavimenta\u00e7\u00e3o, galerias e implanta\u00e7\u00e3o de sem\u00e1foro. Os recursos, conquistados em Bras\u00edlia por meio da articula\u00e7\u00e3o do deputado federal Zeca Dirceu (PT-PR), somam R$ 68.668,60 e representam 10% do valor total do conv\u00eanio, estipulado em R$ 686.000,00.<\/p>\n","protected":false},"author":1,"featured_media":27504,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6441],"class_list":["post-27505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-ministerio-das-cidades-repassa-r-68-mil-para-cruzeiro-do-oeste"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=27505"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/27504"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=27505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=27505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=27505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}