{"id":27449,"date":"2011-10-31T00:00:00","date_gmt":"2011-10-31T02:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/mais-dinheiro-para-a-saude-dos-paranaenses\/"},"modified":"2011-10-31T00:00:00","modified_gmt":"2011-10-31T02:00:00","slug":"mais-dinheiro-para-a-saude-dos-paranaenses","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/mais-dinheiro-para-a-saude-dos-paranaenses\/","title":{"rendered":"Mais dinheiro para a sa\u00fade dos paranaenses"},"content":{"rendered":"<p class=\"MsoNormal\">Mais uma boa not&iacute;cia que temos para comemorar em rela&ccedil;&atilde;o aos investimentos na sa&uacute;de do povo paranaense. Desde a semana passada, eu e minha equipe de mandato estamos comunicando aos prefeitos e t&eacute;cnicos das Prefeituras do nosso Estado que o Minist&eacute;rio da Sa&uacute;de vai repassar R$ 1.300 a mais por m&ecirc;s, para cada equipe do Programa Sa&uacute;de da Fam&iacute;lia, aos munic&iacute;pios cadastrados no Programa Mais Qualidade.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">A sa&uacute;de bucal, outra importante vertente do sistema de aten&ccedil;&atilde;o b&aacute;sica, tamb&eacute;m ter&aacute; acr&eacute;scimo nos repasses. Cada equipe de sa&uacute;de bucal vinculada ao Programa Sa&uacute;de da Fam&iacute;lia ter&aacute; direito a R$ 400 a mais, todo m&ecirc;s, para aumentar a qualidade do atendimento prestado &agrave; popula&ccedil;&atilde;o.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Os valores foram garantidos em portaria do Minist&eacute;rio da Sa&uacute;de, publicada no Di&aacute;rio Oficial da Uni&atilde;o. &Eacute; sempre bom lembrar que estes valores correspondem a um acr&eacute;scimo de 20%, concedido a todos os munic&iacute;pios no momento da ades&atilde;o ao Programa Nacional de Melhoria do Acesso e da Qualidade da Aten&ccedil;&atilde;o B&aacute;sica (PMAQ-AB).<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Mas este aumento pode chegar a at&eacute; 100%, dobrando os recursos dispon&iacute;veis para atendimento do Programa Sa&uacute;de da Fam&iacute;lia, se os munic&iacute;pios comprovarem avan&ccedil;os na qualidade do atendimento &agrave; popula&ccedil;&atilde;o. Os resultados de cada cidade ser&atilde;o medidos em processo de certifica&ccedil;&atilde;o comandado pelo Minist&eacute;rio da Sa&uacute;de.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mais uma boa not\u00edcia que temos para comemorar em rela\u00e7\u00e3o aos investimentos na sa\u00fade do povo paranaense. Desde a semana passada, eu e minha equipe de mandato estamos comunicando aos prefeitos e t\u00e9cnicos das Prefeituras do nosso Estado que o Minist\u00e9rio da Sa\u00fade vai repassar R$ 1.300 a mais por m\u00eas, para cada equipe do Programa Sa\u00fade da Fam\u00edlia, aos munic\u00edpios cadastrados no Programa Mais Qualidade.<\/p>\n","protected":false},"author":1,"featured_media":27448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6419],"class_list":["post-27449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-mais-dinheiro-para-a-saude-dos-paranaenses"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=27449"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27449\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/27448"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=27449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=27449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=27449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}