{"id":27315,"date":"2011-11-07T00:00:00","date_gmt":"2011-11-07T02:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/deputados-do-pt-parana-debatem-estrategias-para-eleicoes-municipais\/"},"modified":"2011-11-07T00:00:00","modified_gmt":"2011-11-07T02:00:00","slug":"deputados-do-pt-parana-debatem-estrategias-para-eleicoes-municipais","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/deputados-do-pt-parana-debatem-estrategias-para-eleicoes-municipais\/","title":{"rendered":"Deputados do PT Paran\u00e1 debatem estrat\u00e9gias para elei\u00e7\u00f5es municipais"},"content":{"rendered":"<p>&nbsp;O PT Paran&aacute; realizou na manh&atilde; desta segunda-feira, 7, na sede do diret&oacute;rio em Curitiba, uma reuni&atilde;o para debater a organiza&ccedil;&atilde;o do partido para as elei&ccedil;&otilde;es municipais de 2012. Participaram do encontro secret&aacute;rios estaduais do PT al&eacute;m dos deputados federais Andr&eacute; Vargas e Zeca Dirceu e deputados estaduais Luciana Rafagnin, Tadeu Veneri, Toninho Wanscheer, P&eacute;ricles de Mello e Elton Welter. O presidente do diret&oacute;rio estadual, deputado Enio Verri, foi representado pelo secret&aacute;rio de Finan&ccedil;as do PT\/PR, Zeno Minuzzo.<\/p>\n<p class=\"MsoNormal\"><o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">&nbsp;Com o objetivo de estabelecer estrat&eacute;gias visando a elei&ccedil;&atilde;o de, no m&iacute;nimo, 50 prefeitos e 400 vereadores em 2012, o PT\/PR criu um grupo de trabalho interno com o objetivo de fazer um levantamento da conjuntura pol&iacute;tica de cada munic&iacute;pio. A inten&ccedil;&atilde;o &eacute; reunir informa&ccedil;&otilde;es que possam fundamentar as decis&otilde;es do partido para alcan&ccedil;ar as metas nas elei&ccedil;&otilde;es do ano que vem. Durante a reuni&atilde;o, foi apresentado uma pr&eacute;via deste estudo.<\/p>\n<p class=\"MsoNormal\">Os participantes tamb&eacute;m debateram sobre a import&acirc;ncia do PEDEx 2011 para a constitui&ccedil;&atilde;o dos novos diret&oacute;rios municipais. As comiss&otilde;es provis&oacute;rias do PT no Paran&aacute; que n&atilde;o realizarem o PEDEx em dezembro n&atilde;o poder&atilde;o ter candidatos nas elei&ccedil;&otilde;es municipais.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">&nbsp;Para dar continuidade ao debate de mobiliza&ccedil;&atilde;o do partido, ficou decidido que uma nova reuni&atilde;o ser&aacute; realizada entre os deputados e os secret&aacute;rios estaduais no dia 12 de dezembro, &agrave;s 8 horas, na sede do diret&oacute;rio em Curitiba.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O PT Paran\u00e1 realizou na manh\u00e3 desta segunda-feira, 7, na sede do diret\u00f3rio em Curitiba, uma reuni\u00e3o para debater a organiza\u00e7\u00e3o do partido para as elei\u00e7\u00f5es municipais de 2012. Participaram do encontro secret\u00e1rios estaduais do PT al\u00e9m dos deputados federais Andr\u00e9 Vargas e Zeca Dirceu e deputados estaduais Luciana Rafagnin, Tadeu Veneri, Toninho Wanscheer, P\u00e9ricles de Mello e Elton Welter. O presidente do diret\u00f3rio estadual, deputado Enio Verri, foi representado pelo secret\u00e1rio de Finan\u00e7as do PT\/PR, Zeno Minuzzo.<\/p>\n","protected":false},"author":1,"featured_media":27314,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6360],"class_list":["post-27315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-deputados-do-pt-parana-debatem-estrategias-para-eleicoes-municipais"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=27315"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27315\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/27314"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=27315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=27315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=27315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}