{"id":27241,"date":"2011-11-10T00:00:00","date_gmt":"2011-11-10T02:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/em-pauta-as-rodovias-do-parana\/"},"modified":"2011-11-10T00:00:00","modified_gmt":"2011-11-10T02:00:00","slug":"em-pauta-as-rodovias-do-parana","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/em-pauta-as-rodovias-do-parana\/","title":{"rendered":"Em pauta as rodovias do Paran\u00e1"},"content":{"rendered":"<p>&nbsp;Na &uacute;ltima segunda-feira, 07, estive na superintend&ecirc;ncia do DNIT do Paran&aacute;, em Curitiba, onde participei de uma audi&ecirc;ncia com o Superintendente Estadual, Jos&eacute; da Silva Tiago.<\/p>\n<p class=\"MsoNormal\">Na pauta assuntos sobre investimentos na infraestrutura de transportes do Paran&aacute;, principalmente no que se referem &agrave;s rodovias, as &uacute;ltimas provid&ecirc;ncias sobre as inst&acirc;ncias da pavimenta&ccedil;&atilde;o da BR 487, a estrada Boiadeira. Aproveitei a reuni&atilde;o para tratar dos investimentos em outras rodovias federais, tamb&eacute;m importantes para o estado, como a BR 153, BR 163 e BR 158. &nbsp;Ou&ccedil;a a reportagem.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na \u00faltima segunda-feira, 07, estive na superintend\u00eancia do DNIT do Paran\u00e1, em Curitiba, onde participei de uma audi\u00eancia com o Superintendente Estadual, Jos\u00e9 da Silva Tiago.  Ou\u00e7a a reportagem.<\/p>\n","protected":false},"author":1,"featured_media":27240,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6334],"class_list":["post-27241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-em-pauta-as-rodovias-do-parana"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=27241"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27241\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/27240"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=27241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=27241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=27241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}