{"id":27137,"date":"2011-11-17T00:00:00","date_gmt":"2011-11-17T02:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/cruzeiro-do-oeste-recebera-recursos-federais-para-obras-de-saneamento\/"},"modified":"2011-11-17T00:00:00","modified_gmt":"2011-11-17T02:00:00","slug":"cruzeiro-do-oeste-recebera-recursos-federais-para-obras-de-saneamento","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/cruzeiro-do-oeste-recebera-recursos-federais-para-obras-de-saneamento\/","title":{"rendered":"Cruzeiro do Oeste receber\u00e1 recursos federais para obras de saneamento"},"content":{"rendered":"<p>&nbsp;O Minist&eacute;rio das Cidades divulgou a lista de munic&iacute;pios selecionados para receber recursos destinados a empreendimentos de saneamento, por meio de financiamento para a Sanepar.&nbsp; O processo seletivo comp&otilde;e a segunda etapa do Programa de Acelera&ccedil;&atilde;o do Crescimento (PAC) e contemplou apenas pequenos munic&iacute;pios, com popula&ccedil;&atilde;o inferior a 50 mil habitantes. O munic&iacute;pio de Cruzeiro do Oeste foi selecionado para receber recursos na ordem de R$ 3,8 milh&otilde;es, para implanta&ccedil;&atilde;o de sistema de esgotamento sanit&aacute;rio.<\/p>\n<p class=\"MsoNormal\"><o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">O deputado federal Zeca Dirceu (PT-PR), que vinha priorizando o munic&iacute;pio nas tratativas junto ao Minist&eacute;rio, comemora a conquista. &ldquo;Investir em saneamento, melhorando os sistemas de abastecimento de &aacute;gua e ampliando as redes coletoras e de tratamento de esgoto &eacute; investir em sa&uacute;de. Organismos internacionais j&aacute; comprovaram que, a cada R$ 1 investido em saneamento, deixa-se de gastar em torno de R$ 8 em tratamento de doen&ccedil;as&rdquo;, enfatizou o parlamentar.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Para o prefeito Valter Rocha, o Valtinho, os investimentos em saneamento v&ecirc;m em excelente momento. &quot;Temos como meta chegar a 80% de cobertura no tratamento de esgoto de Cruzeiro do Oeste at&eacute; 2012, e com estes novos recursos certamente vamos cumprir esta meta, e quem sabe at&eacute; super&aacute;-la&quot;, disse o prefeito.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">No Paran&aacute;, foram selecionadas 41 propostas no valor de empr&eacute;stimo de R$ 132 milh&otilde;es, beneficiando 39 munic&iacute;pios. Quanto &agrave;s modalidades, foram selecionadas 16 propostas de abastecimento de &aacute;gua e 25 propostas de esgotamento sanit&aacute;rio.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Os proponentes que tiveram as propostas selecionadas dever&atilde;o apresentar, junto aos agentes financeiros, os projetos de engenharia, documenta&ccedil;&atilde;o t&eacute;cnica, jur&iacute;dica e institucional at&eacute; 27 de janeiro de 2012.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio das Cidades divulgou a lista de munic\u00edpios selecionados para receber recursos destinados a empreendimentos de saneamento, por meio de financiamento para a Sanepar.  O processo seletivo comp\u00f5e a segunda etapa do Programa de Acelera\u00e7\u00e3o do Crescimento (PAC) e contemplou apenas pequenos munic\u00edpios, com popula\u00e7\u00e3o inferior a 50 mil habitantes. O munic\u00edpio de Cruzeiro do Oeste foi selecionado para receber recursos na ordem de R$ 3,8 milh\u00f5es, para implanta\u00e7\u00e3o de sistema de esgotamento sanit\u00e1rio.<\/p>\n","protected":false},"author":1,"featured_media":27136,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6290],"class_list":["post-27137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-cruzeiro-do-oeste-recebera-recursos-federais-para-obras-de-saneamento"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=27137"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27137\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/27136"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=27137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=27137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=27137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}