{"id":27065,"date":"2011-11-22T00:00:00","date_gmt":"2011-11-22T02:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/fns-transfere-r-1492-milhoes-ao-parana\/"},"modified":"2011-11-22T00:00:00","modified_gmt":"2011-11-22T02:00:00","slug":"fns-transfere-r-1492-milhoes-ao-parana","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/fns-transfere-r-1492-milhoes-ao-parana\/","title":{"rendered":"FNS transfere R$ 149,2 milh\u00f5es ao Paran\u00e1"},"content":{"rendered":"<p>Recurso corresponde ao total das transfer&ecirc;ncias fundo a fundo, efetuadas na primeira quinzena de novembro. Todos os munic&iacute;pios do estado foram beneficiados <br \/>\nO estado e os 399 munic&iacute;pios do estado do Paran&aacute; receberam, na primeira quinzena de novembro, o total R$ 149,2 milh&otilde;es para aplica&ccedil;&atilde;o em a&ccedil;&otilde;es de sa&uacute;de. <\/p>\n<p>Desse montante, transferido pelo Fundo Nacional de Sa&uacute;de (FNS) para os fundos estadual e municipais de sa&uacute;de, R$ 118,9 milh&otilde;es (79,6%) foram destinados para bloco de financiamento da M&eacute;dia e Alta Complexidade Hospitalar (MAC), que incluem o custeio de procedimentos como transplantes e quimioterapia. Al&eacute;m disso, o recurso deste bloco financia hospitais de pequeno porte, centros de especialidades odontol&oacute;gicas, laborat&oacute;rios de pr&oacute;tese dent&aacute;ria e do programa SAMU, entre outras a&ccedil;&otilde;es.<\/p>\n<p>Para o bloco de Aten&ccedil;&atilde;o B&aacute;sica, foram repassados R$ 17,8 milh&otilde;es,nos primeiros quinze dias do novembro. O recurso financia a&ccedil;&otilde;es b&aacute;sicas de sa&uacute;de e de programas como Sa&uacute;de da Fam&iacute;lia, Agentes Comunit&aacute;rios de Sa&uacute;de, Sa&uacute;de Bucal, entre outros.<\/p>\n<p>O terceiro bloco com maior volume de recursos foi o de Vigil&acirc;ncia em Sa&uacute;de (R$ 11,2 milh&otilde;es). Este bloco financia a&ccedil;&otilde;es de preven&ccedil;&atilde;o a doen&ccedil;as, no &acirc;mbito da vigil&acirc;ncia epidemiol&oacute;gica e ambiental em sa&uacute;de.&nbsp; <\/p>\n<p>Dez munic&iacute;pios paranaenses receberam recursos no bloco de Investimento, que financia a implanta&ccedil;&atilde;o de Unidade B&aacute;sica de Sa&uacute;de (UBS), aquisi&ccedil;&atilde;o de materiais, constru&ccedil;&atilde;o de Unidades de Pronto Atendimento (UPA), Salas de Estabiliza&ccedil;&atilde;o (UPA\/SE), entre outras a&ccedil;&otilde;es. O total transferido foi de R$ 1,1 milh&atilde;o.<\/p>\n<p>Para a implanta&ccedil;&atilde;o de UBS, foram repassados R$ 20 mil ao munic&iacute;pio de Rio Bonito do Igua&ccedil;u (primeira parcela). As cidades de Apucarana e Pinhais receberam, cada uma, R$ 260 mil, correspondente &agrave; segunda parcela de implanta&ccedil;&atilde;o das unidades. J&aacute; o munic&iacute;pio de Dois Vizinhos, que tamb&eacute;m est&aacute; implantando uma UBS, recebeu a segunda parcela, no valor de R$ 130 mil.<\/p>\n<p>As cidades de Alto Piqueri, Arapongas, Bocai&uacute;va, Campo Mour&atilde;o, Doutor Ulysses e Ortigueira receberam quase R$ 500 mil para a aquisi&ccedil;&atilde;o de equipamentos e material permanente. O objetivo &eacute; a estrutura&ccedil;&atilde;o da rede de servi&ccedil;os de aten&ccedil;&atilde;o b&aacute;sica de sa&uacute;de local.&nbsp; <\/p>\n<p>O montante transferido para o financiamento e manuten&ccedil;&atilde;o da Assist&ecirc;ncia Farmac&ecirc;utica totalizou R$ 120 mil, destinados a tr&ecirc;s componentes: Assist&ecirc;ncia Farmac&ecirc;utica B&aacute;sica, Assist&ecirc;ncia Farmac&ecirc;utica Estrat&eacute;gica e o componente Especializado da Assist&ecirc;ncia Farmac&ecirc;utica.<\/p>\n<p>Para a Assist&ecirc;ncia Farmac&ecirc;utica B&aacute;sica s&atilde;o repassados recursos para a aquisi&ccedil;&atilde;o de medicamentos e insumos. J&aacute; o recurso da Assist&ecirc;ncia Farmac&ecirc;utica Estrat&eacute;gia custeia a&ccedil;&otilde;es como controle de endemias, antirretrovirais do Programa DST e Aids, sangue e Hemoderivados e imunobiol&oacute;gicos, entre outras. O componente Especializado se refere aos casos mais complexos e de alto custo &#8211; medicamentos para tratamento de Alzheimer, osteoporose, card&iacute;acos cr&ocirc;nicos, entre outros.<\/p>\n<p><strong>Capital &ndash;<\/strong> Curitiba recebeu R$ 88,4 milh&otilde;es para a gest&atilde;o dos servi&ccedil;os do Sistema &Uacute;nico de Sa&uacute;de (SUS). Isso representou 59,2% do total repassado para os munic&iacute;pios paranaenses.<br \/>\nDo total transferido para a capital, R$ 82,1 milh&otilde;es (92,8%) foram para o financiamento de a&ccedil;&otilde;es no bloco de M&eacute;dia e Alta Complexidade, sendo R$ 52,1 milh&otilde;es para o Fundo Estadual de Sa&uacute;de.<\/p>\n<p>Outros R$ 2 milh&otilde;es foram transferidos ao Estado para a&ccedil;&otilde;es de Promo&ccedil;&atilde;o da Sa&uacute;de, no &acirc;mbito da Vigil&acirc;ncia em Sa&uacute;de. Ainda neste bloco, foram repassados R$ 20 mil para o N&uacute;cleo Hospitalar de Epidemiologia do Hospital das Cl&iacute;nicas, ligado &agrave; Universidade Federal do Paran&aacute;.<\/p>\n<p>A segunda cidade com maior aporte de recursos foi Londrina &#8211; R$ 12,9 milh&otilde;es. Destes, R$ 11,5 milh&otilde;es foram o MAC. A terceira cidade a receber mais recursos foi Maring&aacute; &#8211; R$ 8,5 milh&otilde;es, dos quais R$ 7,5 milh&otilde;es para a&ccedil;&otilde;es do bloco da MAC.<\/p>\n<p>A transfer&ecirc;ncia consiste no repasse de valores, regular e autom&aacute;tico, diretamente do Fundo Nacional de Sa&uacute;de (FNS) para os estados e munic&iacute;pios.<\/p>\n<p>\nFonte: Portal da Sa&uacute;de<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Recurso corresponde ao total das transfer\u00eancias fundo a fundo, efetuadas na primeira quinzena de novembro. Todos os munic\u00edpios do estado foram beneficiados<br \/>\nO estado e os 399 munic\u00edpios do estado do Paran\u00e1 receberam, na primeira quinzena de novembro, o total R$ 149,2 milh\u00f5es para aplica\u00e7\u00e3o em a\u00e7\u00f5es de sa\u00fade.<\/p>\n","protected":false},"author":1,"featured_media":27064,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[980,86,6259],"class_list":["post-27065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-fns","tag-parana","tag-transferencias"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=27065"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27065\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/27064"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=27065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=27065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=27065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}