{"id":27047,"date":"2011-11-23T00:00:00","date_gmt":"2011-11-23T02:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/execucao-do-pac-2-aumenta-em-66-e-113-das-obras-previstas-para-2014-estao-prontas\/"},"modified":"2011-11-23T00:00:00","modified_gmt":"2011-11-23T02:00:00","slug":"execucao-do-pac-2-aumenta-em-66-e-113-das-obras-previstas-para-2014-estao-prontas","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/execucao-do-pac-2-aumenta-em-66-e-113-das-obras-previstas-para-2014-estao-prontas\/","title":{"rendered":"Execu\u00e7\u00e3o do PAC 2 aumenta em 66% e 11,3% das obras previstas para 2014 est\u00e3o prontas"},"content":{"rendered":"<p>&nbsp;O segundo balan&ccedil;o do Programa de Acelera&ccedil;&atilde;o do Crescimento (PAC 2) &ndash; , apresentado na ter&ccedil;a-feira (22), revela um aumento de 66% na execu&ccedil;&atilde;o or&ccedil;ament&aacute;ria entre junho e setembro deste ano: de R$ 86,4 bilh&otilde;es para R$ 143,6 bilh&otilde;es. Entre janeiro e setembro de 2011, foram R$ 80,2 bilh&otilde;es para t&eacute;rmino de obras, que j&aacute; est&aacute; em 11,3% do total previsto para concluir at&eacute; 2014. A execu&ccedil;&atilde;o at&eacute; 30 de setembro deste ano representa 15% do total previsto para o per&iacute;odo de 2011 a 2014.<\/p>\n<p class=\"MsoNormal\"><o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">At&eacute; setembro deste ano, volume de pagamento do Or&ccedil;amento Geral da Uni&atilde;o foi 22% superior ao pago no mesmo per&iacute;odo de 2010: de R$ 17,7 bilh&otilde;es para R$ 21,6 bilh&otilde;es.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Do total de R$ 143,6 bilh&otilde;es executados, R$ 55,2 bilh&otilde;es correspondem ao financiamento habitacional a pessoa f&iacute;sica; R$ 41,4 bilh&otilde;es ao executado pelas empresas estatais; R$ 25,6 bilh&otilde;es ao setor privado; e R$ 13,2 bilh&otilde;es ao Or&ccedil;amento Geral da Uni&atilde;o (OGU) Fiscal e Seguridade. Os valores restantes se referem ao programa Minha Casa, Minha Vida, R$ 5,4 bilh&otilde;es; financiamento ao setor p&uacute;blico, R$ 2 bilh&otilde;es; e contrapartidas de estados e munic&iacute;pios, R$ 700 milh&otilde;es.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">O PAC2 executar&aacute; R$ 955 bilh&otilde;es entre 2011 e 2014. Nesse per&iacute;odo, o valor previsto para conclus&atilde;o de obras totaliza R$ 708 bilh&otilde;es ou 74% do total. As demais obras, 26%, ser&atilde;o conclu&iacute;das ap&oacute;s 2014.&nbsp; Entre elas est&atilde;o a Usina Hidrel&eacute;trica Belo Monte (PA), o Complexo Petroqu&iacute;mico do Rio de Janeiro (Comperj) e a Ferrovia de Integra&ccedil;&atilde;o do Centro-Oeste.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">&ldquo;Do ponto de vista da infraestrutura do Pa&iacute;s, estamos dando passos necess&aacute;rios para dar conta dos desafios que esse setor nos coloca para seguir crescendo&rdquo;, afirma a ministra do Planejamento, Miriam Belchior.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Monitoramento &#8211; Considerando apenas os eixos Transportes, Energia, Mobilidade Urbana, Luz para Todos e Recursos H&iacute;dricos, at&eacute; 30 de setembro de 2011, 3% das a&ccedil;&otilde;es monitoradas foram conclu&iacute;das e 86% estavam em ritmo adequado &#8211; de acordo com o crit&eacute;rio de volume de recursos envolvidos. <o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Efeito antic&iacute;clico<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">O cen&aacute;rio macroecon&ocirc;mico tra&ccedil;ado no segundo balan&ccedil;o do PAC 2 avalia a necessidade de manter o programa de investimento em infraestrutura, devido ao ambiente de incertezas nos pa&iacute;ses avan&ccedil;ados. &ldquo;A estrat&eacute;gia &eacute; fortalecer os fundamentos da economia, com estabilidade macroecon&ocirc;mica, qualifica&ccedil;&atilde;o da for&ccedil;a de trabalho, est&iacute;mulos &agrave; inova&ccedil;&atilde;o tecnol&oacute;gica e investimentos em infraestrutura, com o objetivo de promover o ingresso de investimentos produtivos e de adensamento de cadeias industriais&rdquo;, descreve o relat&oacute;rio.<\/p>\n<p>Secom<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O segundo balan\u00e7o do Programa de Acelera\u00e7\u00e3o do Crescimento (PAC 2) \u2013 , apresentado na ter\u00e7a-feira (22), revela um aumento de 66% na execu\u00e7\u00e3o or\u00e7ament\u00e1ria entre junho e setembro deste ano: de R$ 86,4 bilh\u00f5es para R$ 143,6 bilh\u00f5es. Entre janeiro e setembro de 2011, foram R$ 80,2 bilh\u00f5es para t\u00e9rmino de obras, que j\u00e1 est\u00e1 em 11,3% do total previsto para concluir at\u00e9 2014. A execu\u00e7\u00e3o at\u00e9 30 de setembro deste ano representa 15% do total previsto para o per\u00edodo de 2011 a 2014.<\/p>\n","protected":false},"author":1,"featured_media":27046,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6252,6251],"class_list":["post-27047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-3-das-obras-previstas-para-2014-estao-prontas","tag-execucao-do-pac-2-aumenta-em-66-e-11"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=27047"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27047\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/27046"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=27047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=27047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=27047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}