{"id":27041,"date":"2011-11-23T00:00:00","date_gmt":"2011-11-23T02:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/nova-londrina-garante-r-1-milhao-em-verbas-federais-para-ampliar-a-rede-de-esgoto\/"},"modified":"2011-11-23T00:00:00","modified_gmt":"2011-11-23T02:00:00","slug":"nova-londrina-garante-r-1-milhao-em-verbas-federais-para-ampliar-a-rede-de-esgoto","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/nova-londrina-garante-r-1-milhao-em-verbas-federais-para-ampliar-a-rede-de-esgoto\/","title":{"rendered":"Nova Londrina garante R$ 1 milh\u00e3o, em verbas federais, para ampliar a rede de esgoto"},"content":{"rendered":"<p>&nbsp;O munic&iacute;pio de Nova Londrina recebe do Minist&eacute;rio das Cidades, atrav&eacute;s de financiamento pela Sanepar, R$ 1 milh&atilde;o para a amplia&ccedil;&atilde;o das obras no Sistema de Esgotamento Sanit&aacute;rio. As tratativas conduzidas pelo deputado federal Zeca Dirceu ir&atilde;o garantir novos 10 km de rede coletora de esgoto para a popula&ccedil;&atilde;o do munic&iacute;pio.<\/p>\n<p class=\"MsoNormal\"><o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">A verba foi garantida para Nova Londrina&nbsp;&nbsp;por meio da articula&ccedil;&atilde;o pol&iacute;tica do deputado federal Zeca Dirceu (PT-PR), que falou sobre a import&acirc;ncia dos recursos. &ldquo;&Eacute; mais um investimento que conseguimos articular com sucesso para o munic&iacute;pio. Fico feliz em realizar as tratativas por que o impacto &eacute; vis&iacute;vel. Investir em saneamento &eacute; investir em sa&uacute;de para a popula&ccedil;&atilde;o&rdquo;, afirmou Zeca Dirceu.<\/p>\n<p>O&nbsp;Minist&eacute;rio das Cidades apresentou a lista final de propostas selecionadas para empreendimentos de saneamento em munic&iacute;pios com popula&ccedil;&atilde;o inferior a 50 mil habitantes. O processo seletivo comp&otilde;e a segunda etapa do Programa de Acelera&ccedil;&atilde;o do Crescimento (PAC), e Nova Londrina&nbsp; &nbsp;est&aacute; entre os munic&iacute;pios que ter&atilde;o seu Sistema de Esgotamento Sanit&aacute;rio (SES) em obras a partir desse repasse, que ser&aacute; conduzido pela Sanepar, na ordem de R$ 1 milh&atilde;o.<\/p>\n<p class=\"MsoNormal\"><o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">No projeto est&aacute; a amplia&ccedil;&atilde;o do SES, com a execu&ccedil;&atilde;o de 10 Km de rede coletora de esgoto, trabalho socioambiental e 500 liga&ccedil;&otilde;es prediais para o munic&iacute;pio. Foram selecionadas 134 propostas no valor de empr&eacute;stimo de R$ 1, 127 bilh&atilde;o, beneficiando 125 munic&iacute;pios em 13 unidades do pa&iacute;s. Quanto &agrave;s modalidades, foram selecionadas 51 propostas de abastecimento de &aacute;gua, valor de empr&eacute;stimo de R$ 368,6 milh&otilde;es e 83 propostas de esgotamento sanit&aacute;rio, valor de empr&eacute;stimo de R$ 758,7 milh&otilde;es.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O munic\u00edpio de Nova Londrina recebe do Minist\u00e9rio das Cidades, atrav\u00e9s de financiamento pela Sanepar, R$ 1 milh\u00e3o para a amplia\u00e7\u00e3o das obras no Sistema de Esgotamento Sanit\u00e1rio. As tratativas conduzidas pelo deputado federal Zeca Dirceu ir\u00e3o garantir novos 10 km de rede coletora de esgoto para a popula\u00e7\u00e3o do munic\u00edpio.<\/p>\n","protected":false},"author":1,"featured_media":27040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6246,6245,6247],"class_list":["post-27041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-em-verbas-federais","tag-nova-londrina-garante-r-1-milhao","tag-para-ampliar-a-rede-de-esgoto-do-mu"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=27041"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/27041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/27040"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=27041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=27041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=27041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}