{"id":26949,"date":"2011-11-29T00:00:00","date_gmt":"2011-11-29T02:00:00","guid":{"rendered":"https:\/\/www.zecadirceu.com.br\/sus-trata-97-dos-diagnosticados-com-aids\/"},"modified":"2011-11-29T00:00:00","modified_gmt":"2011-11-29T02:00:00","slug":"sus-trata-97-dos-diagnosticados-com-aids","status":"publish","type":"post","link":"https:\/\/teste.bsb.br\/zeca\/sus-trata-97-dos-diagnosticados-com-aids\/","title":{"rendered":"SUS trata 97% dos diagnosticados com Aids"},"content":{"rendered":"<p>&nbsp;O tratamento antirretroviral pelo Sistema &Uacute;nico de Sa&uacute;de (SUS) &eacute; oferecido a 97% dos brasileiros diagnosticados com Aids. O dado integra o &uacute;ltimo relat&oacute;rio do Programa Conjunto das Na&ccedil;&otilde;es Unidas sobre o HIV\/Aids (Unaids), divulgado em 21 de novembro. Neste documento, os investimentos e as pr&aacute;ticas do governo brasileiro no tratamento da Aids s&atilde;o destacados.<\/p>\n<p class=\"MsoNormal\"><o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">A Unaids aponta o modelo do Brasil de preven&ccedil;&atilde;o do HIV e assist&ecirc;ncia como um dos melhores do mundo, especialmente em rela&ccedil;&atilde;o a popula&ccedil;&otilde;es mais vulner&aacute;veis. Para o diretor do Unaids no Brasil, Pedro Chequer, o resultado se deve &agrave;s a&ccedil;&otilde;es relacionadas &agrave; Aids serem pol&iacute;ticas de Estado. O SUS tem investido na preven&ccedil;&atilde;o e amplia&ccedil;&atilde;o da testagem, do acesso ao tratamento antirretroviral, al&eacute;m de capacitar profissionais de sa&uacute;de, o que mant&eacute;m sob controle a epidemia de aids no Brasil. <o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Teste &#8211; O ministro da Sa&uacute;de, Alexandre Padilha, destaca o &ldquo;Fique Sabendo&rdquo;, uma estrat&eacute;gia do SUS para estimular e facilitar a realiza&ccedil;&atilde;o do teste de Aids pela popula&ccedil;&atilde;o. &ldquo;Estamos investindo na expans&atilde;o da testagem r&aacute;pida para garantir que o diagn&oacute;stico seja o mais breve poss&iacute;vel, com a&ccedil;&otilde;es do Fique Sabendo. Quanto mais cedo o v&iacute;rus &eacute; descoberto, mais cedo tem in&iacute;cio o tratamento, proporcionando qualidade de vida para quem vive com a doen&ccedil;a&rdquo;, explicou.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Cai n&uacute;mero de novos casos e de morte entre crian&ccedil;as at&eacute; cinco anos<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">O Boletim Epidemiol&oacute;gico Aids\/DST 2011, divulgado nesta segunda-feira (28), revela que a taxa de transmiss&atilde;o da m&atilde;e infectada para a crian&ccedil;a diminuiu em 41% nos &uacute;ltimos 12 anos. J&aacute; o coeficiente de mortalidade nesta faixa et&aacute;ria caiu em 62,5%. <o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">A estimativa de pessoas infectadas pelo HIV continua est&aacute;vel em cerca de 0,6% da popula&ccedil;&atilde;o. J&aacute; o n&uacute;mero de novos casos notificados teve uma pequena redu&ccedil;&atilde;o: em 2009, a taxa era de 18.8\/100 mil habitantes e caiu para 17,9\/100 mil, em 2010. Essa queda, em n&uacute;meros absolutos, mostra que no ano passado foram 34,2 mil novos casos de Aids, ante 35,9 mil em 2009. De 1980 a junho de 2011, 608.230 pessoas foram infectadas. <o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">No ano passado, o n&uacute;mero de pessoas que morreram em decorr&ecirc;ncia da doen&ccedil;a foi de 11.965, um pouco menor que em 2009, quando morreram 12.097. O total de pessoas v&iacute;timas da Aids desde 1980, em todo o Pa&iacute;s, &eacute; 241.469.<o:p><\/o:p><\/p>\n<p class=\"MsoNormal\">Campanha &#8211; Nos &uacute;ltimos 12 anos, a porcentagem de casos na popula&ccedil;&atilde;o de 15 a 24 anos caiu, mas n&atilde;o igualmente. Entre os homossexuais nesta faixa et&aacute;ria houve aumento de 10,1%. No ano passado, para cada 16 homossexuais de 15 a 24 anos vivendo com aids, havia 10 heterossexuais. Essa rela&ccedil;&atilde;o, em 1998, era de 12 para 10. Este p&uacute;blico ser&aacute; priorizado pelo minist&eacute;rio na campanha do Dia Mundial de Luta.<\/p>\n<p class=\"MsoNormal\"><u>Secom<o:p><\/o:p><\/u><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O tratamento antirretroviral pelo Sistema \u00danico de Sa\u00fade (SUS) \u00e9 oferecido a 97% dos brasileiros diagnosticados com Aids. O dado integra o \u00faltimo relat\u00f3rio do Programa Conjunto das Na\u00e7\u00f5es Unidas sobre o HIV\/Aids (Unaids), divulgado em 21 de novembro. Neste documento, os investimentos e as pr\u00e1ticas do governo brasileiro no tratamento da Aids s\u00e3o destacados.<\/p>\n","protected":false},"author":1,"featured_media":26948,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6200],"class_list":["post-26949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-zeca-dirceu","tag-sus-trata-97-dos-diagnosticados-com-aids"],"_links":{"self":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/26949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/comments?post=26949"}],"version-history":[{"count":0,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/posts\/26949\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media\/26948"}],"wp:attachment":[{"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/media?parent=26949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/categories?post=26949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/teste.bsb.br\/zeca\/wp-json\/wp\/v2\/tags?post=26949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}